{"id":964,"date":"2014-11-18T21:46:36","date_gmt":"2014-11-18T21:46:36","guid":{"rendered":"http:\/\/web.msicom.net\/wordpress\/?p=964"},"modified":"2014-11-18T21:54:59","modified_gmt":"2014-11-18T21:54:59","slug":"novedades-en-mets-amsterdam-2014-nuevo-dualdocker-telescopico","status":"publish","type":"post","link":"https:\/\/web.msicom.net\/wordpress\/noticias\/novedades-en-mets-amsterdam-2014-nuevo-dualdocker-telescopico\/","title":{"rendered":"Novedades en METS Amsterdam 2014: Nuevo DualDocker telesc\u00f3pico"},"content":{"rendered":"<p>Hoy se ha presentado en el <a title=\"METS 2014\" href=\"http:\/\/www.metstrade.com\/Pages\/default.aspx\" target=\"_blank\">Sal\u00f3n METS 2014 Amsterdam<\/a> el nuevo DualDocker telesc\u00f3pico para el amarre de embarcaciones de diferente configuraci\u00f3n en la posici\u00f3n de cornamusas.<\/p>\n<p>Esta novedad permitir\u00e1 a los puertos aprovechar el mismo sistema de amarre DualDocker para embarcaciones que tengan las cornamusas puestas en diferentes posiciones, tan s\u00f3lo bastar\u00e1 con alargar o acortar el DualDocker con el nuevo sistema telesc\u00f3pico.<\/p>\n<p>Adem\u00e1s como complemento a esta innovaci\u00f3n se ha presentado toda una gama de adaptadores de la bola de amarre DualDocker para todo tipo de cornamusas e incluso un nuevo &#8220;Soft Adapter&#8221; para aquellas embarcaciones de mayor porte que utilizan un cabrestante para tensar las amarras al muelle.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/web.msicom.net\/wordpress\/wp-content\/uploads\/2014\/11\/SoftAdapter800.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-966\" src=\"https:\/\/web.msicom.net\/wordpress\/wp-content\/uploads\/2014\/11\/SoftAdapter800-300x147.jpg\" alt=\"Soft Adapter\" width=\"300\" height=\"147\" srcset=\"https:\/\/web.msicom.net\/wordpress\/wp-content\/uploads\/2014\/11\/SoftAdapter800-300x147.jpg 300w, https:\/\/web.msicom.net\/wordpress\/wp-content\/uploads\/2014\/11\/SoftAdapter800.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-965\" src=\"https:\/\/web.msicom.net\/wordpress\/wp-content\/uploads\/2014\/11\/DualDockerTelescopicoconSoftAdapter600-168x300.jpg\" alt=\"DualDockerT elescopico con SoftAdapter 600\" width=\"168\" height=\"300\" srcset=\"https:\/\/web.msicom.net\/wordpress\/wp-content\/uploads\/2014\/11\/DualDockerTelescopicoconSoftAdapter600-168x300.jpg 168w, https:\/\/web.msicom.net\/wordpress\/wp-content\/uploads\/2014\/11\/DualDockerTelescopicoconSoftAdapter600-575x1024.jpg 575w, https:\/\/web.msicom.net\/wordpress\/wp-content\/uploads\/2014\/11\/DualDockerTelescopicoconSoftAdapter600.jpg 600w\" sizes=\"(max-width: 168px) 100vw, 168px\" \/><\/a><\/p>\n<p>Si quieres ver c\u00f3mo funciona el amarre de embarcaciones sin fondeos de popa DualDocker te aconsejamos este interesante v\u00eddeo:<\/p>\n<div style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/jtiWH2pUH1A\" width=\"420\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_toolbar\" href=\"http:\/\/www.hupso.com\/share\/\"><img decoding=\"async\" src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/es\/share-medium.png\" border=\"0\" style=\"padding-top:5px; float:right;\" alt=\"Share\"\/><\/a><script type=\"text\/javascript\">var hupso_services_t=new Array(\"Twitter\",\"Facebook\",\"Google Plus\",\"Linkedin\");var hupso_toolbar_size_t=\"medium\";var hupso_twitter_via = \"MSI_Barcelona\";var hupso_counters_lang = \"en_US\";var hupso_twitter_via=\"MSI_Barcelona\";var hupso_title_t=\"Novedades en METS Amsterdam 2014: Nuevo DualDocker telesc\u00f3pico\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/share_toolbar.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"excerpt":{"rendered":"<p>Hoy se ha presentado en el Sal\u00f3n METS 2014 Amsterdam el nuevo DualDocker telesc\u00f3pico para el amarre de embarcaciones de diferente configuraci\u00f3n en la posici\u00f3n de cornamusas. Esta novedad permitir\u00e1 a los puertos aprovechar el mismo sistema de amarre DualDocker para embarcaciones que tengan las cornamusas puestas en diferentes posiciones, tan s\u00f3lo bastar\u00e1 con alargar o acortar el DualDocker con el nuevo sistema telesc\u00f3pico. Adem\u00e1s como complemento a esta innovaci\u00f3n se ha presentado toda una gama de adaptadores de la bola de amarre DualDocker para todo tipo de cornamusas e incluso un nuevo &#8220;Soft Adapter&#8221; para aquellas embarcaciones de mayor porte que utilizan un cabrestante para tensar las amarras al<\/p>\n<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_toolbar\" href=\"http:\/\/www.hupso.com\/share\/\"><img src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/es\/share-medium.png\" border=\"0\" style=\"padding-top:5px; float:right;\" alt=\"Share\"\/><\/a><script type=\"text\/javascript\">var hupso_services_t=new Array(\"Twitter\",\"Facebook\",\"Google Plus\",\"Linkedin\");var hupso_toolbar_size_t=\"medium\";var hupso_twitter_via = \"MSI_Barcelona\";var hupso_counters_lang = \"en_US\";var hupso_twitter_via=\"MSI_Barcelona\";var hupso_title_t=\"Novedades en METS Amsterdam 2014: Nuevo DualDocker telesc\u00f3pico\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/share_toolbar.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"author":1,"featured_media":965,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,8],"tags":[],"_links":{"self":[{"href":"https:\/\/web.msicom.net\/wordpress\/wp-json\/wp\/v2\/posts\/964"}],"collection":[{"href":"https:\/\/web.msicom.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.msicom.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.msicom.net\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.msicom.net\/wordpress\/wp-json\/wp\/v2\/comments?post=964"}],"version-history":[{"count":2,"href":"https:\/\/web.msicom.net\/wordpress\/wp-json\/wp\/v2\/posts\/964\/revisions"}],"predecessor-version":[{"id":968,"href":"https:\/\/web.msicom.net\/wordpress\/wp-json\/wp\/v2\/posts\/964\/revisions\/968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.msicom.net\/wordpress\/wp-json\/wp\/v2\/media\/965"}],"wp:attachment":[{"href":"https:\/\/web.msicom.net\/wordpress\/wp-json\/wp\/v2\/media?parent=964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.msicom.net\/wordpress\/wp-json\/wp\/v2\/categories?post=964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.msicom.net\/wordpress\/wp-json\/wp\/v2\/tags?post=964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}